{"id":7681,"date":"2026-02-03T09:10:08","date_gmt":"2026-02-03T09:10:08","guid":{"rendered":"https:\/\/www.ressler.at\/out-of-the-passage-to-seize-back-the-sky\/"},"modified":"2026-06-06T12:25:04","modified_gmt":"2026-06-06T12:25:04","slug":"out_of_the_passage","status":"publish","type":"post","link":"https:\/\/www.ressler.at\/de\/out_of_the_passage\/","title":{"rendered":"Out of the Passage to Seize Back the Sky"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Eine Installation im \u00f6ffentlichen Raum von Oliver Ressler<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"672\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-1024x672.jpg\" alt=\"\" class=\"wp-image-7669\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-1024x672.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-300x197.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-768x504.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-1536x1008.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-1210x794.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-1150x754.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-834x547.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-414x272.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web-360x236.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/2_Under_their_wheels_but_unbroken_web.jpg 1701w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, light box, 305 x 200 cm, 2026<\/figcaption><\/figure>\n\n\n\n<p>Die f\u00fcnf Leuchtk\u00e4sten, die in der unterirdischen Fu\u00dfg\u00e4ngerpassage von Tren\u010d\u00edn installiert sind, sind der Beitrag des \u00f6sterreichischen K\u00fcnstlers Oliver Ressler zu &#8220;Green Line&#8221;, die Teil der Europ\u00e4ischen Kulturhauptstadt Tren\u010d\u00edn 2026 ist.<\/p>\n\n\n\n<p>Die Unterf\u00fchrung, die die Altstadt mit dem Fluss verbindet, ist typisch f\u00fcr die st\u00e4dtische Infrastruktur: ein niedriger, dunkler Tunnel, der Fu\u00dfg\u00e4nger*innen unter die Erde zwingt, damit Autos oben ungehindert fahren k\u00f6nnen. Da es nur Treppen und keinen Aufzug gibt, sind \u00e4ltere Menschen und Rollstuhlfahrer*innen davon ausgeschlossen.<\/p>\n\n\n\n<p>Obwohl das umweltsch\u00e4dlichste und lauteste Verkehrsmittel den begrenzten Raum in unseren St\u00e4dten massiv \u00fcberbeansprucht, darf es sich unter freiem Himmel ungehindert bewegen. Fu\u00dfg\u00e4nger*innen hingegen werden in dunkle, unsichere unterirdische R\u00e4ume gedr\u00e4ngt. Die Passage wurde in den 1980er Jahren unter einer vermeintlich klassenlosen Gesellschaft gebaut. Heute trennt eine solche Architektur die Klassen der Menschen, die unter die Erde gedr\u00e4ngt werden, von denen, die sich frei \u00fcber ihnen bewegen d\u00fcrfen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1024x683.jpg\" alt=\"\" class=\"wp-image-7688\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1024x683.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-300x200.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-768x512.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1536x1024.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1920x1280.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1210x807.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-1150x767.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-834x556.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-414x276.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05-360x240.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_05.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oliver Ressler.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1024x768.jpg\" alt=\"\" class=\"wp-image-7702\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1024x768.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-300x225.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-768x576.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1536x1152.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-2048x1536.jpg 2048w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1920x1440.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1210x907.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-1150x862.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-834x625.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-414x310.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oto_Hudec_-360x270.jpg 360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oto Hudec.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"672\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-1024x672.jpg\" alt=\"\" class=\"wp-image-7673\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-1024x672.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-300x197.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-768x504.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-1536x1008.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-1210x794.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-1150x754.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-834x547.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-414x272.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web-360x236.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/1_Act_as_if_it_were_possible_to_radically_web.jpg 1701w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, light box, 305 x 200 cm, 2026<\/figcaption><\/figure>\n\n\n\n<p>\u201eHandle so, als ob es m\u00f6glich w\u00e4re, die Welt radikal zu ver\u00e4ndern\u201c, steht auf einem gelben Absperrband in einer fotografischen Arbeit, die Angela Davis zitiert. Die US-amerikanische Philosophin r\u00e4umt ein, dass wir eine gerechte, egalit\u00e4re, radikal demokratische und befreite Gesellschaft erst aufbauen m\u00fcssten, und betont, dass es keine Alternative zum Kampf gibt.<\/p>\n\n\n\n<p>\u201eUnter ihren R\u00e4dern, aber ungebrochen\u201c, steht auf einem weiteren Absperrband, w\u00e4hrend \u00fcber unseren K\u00f6pfen und im Schatten der Burg Tren\u010d\u00edn Autos vorbeirauschen. \u201eUngebrochen\u201c erinnert an das R\u00e4dern, eine mittelalterliche Foltermethode, die bei \u00f6ffentlichen Hinrichtungen zur Zerst\u00f6rung von K\u00f6rpern als Warnung f\u00fcr andere eingesetzt wurde. Das zerquetschte Fahrrad unter dem schweren Rad ist mehr als nur ein Symbol f\u00fcr ein unterdr\u00fcckerisches System: Es verwandelt eine Szene der Zerst\u00f6rung in eine Szene des Durchhalteverm\u00f6gens. Einzelne Menschen k\u00f6nnen get\u00f6tet werden, aber unser kollektiver Widerstand bleibt bestehen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"672\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-1024x672.jpg\" alt=\"\" class=\"wp-image-7671\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-1024x672.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-300x197.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-768x504.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-1536x1008.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-1210x794.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-1150x754.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-834x547.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-414x272.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web-360x236.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/3_We_are_all_in_the_passage_web.jpg 1701w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, light box, 305 x 200 cm, 2026<\/figcaption><\/figure>\n\n\n\n<p>Andere fotografische Arbeiten lassen eine Zukunft jenseits des Zeitalters des fossilen Kapitalismus erahnen: eine Zeit, in der die Dominanz der Autos und die brutalen architektonischen Formen, die mit ihnen gewachsen sind, endlich hinter uns liegen werden. In dieser imagin\u00e4ren Zukunft liegt der Wert nicht im Besitz von Autos, sondern in der Freiheit, sich ohne sie sicher, einfach und nachhaltig fortbewegen zu k\u00f6nnen. Wohlstand erscheint hier als eine F\u00fclle von \u00f6ffentlichem Raum, frischer Luft, zuverl\u00e4ssigen und gut gestalteten \u00f6ffentlichen Verkehrsmitteln und Fahrradwegen.<\/p>\n\n\n\n<p>&#8220;Out of the Passage to Seize Back the Sky&#8221; bekr\u00e4ftigt die Notwendigkeit, nach den Sternen zu greifen und das Recht, sich in der Stadt fortzubewegen, ohne vom Autoverkehr terrorisiert zu werden. Der Besitz eines Privatwagens ist n\u00e4mlich mehr als nur eine lokale Katastrophe. Als eine der Hauptursachen f\u00fcr CO2-Emissionen und die damit verbundene globale Erhitzung hat er weltweit enorme Auswirkungen, die sich st\u00e4ndig verschlimmern. Die weltweit steigenden Temperaturen t\u00f6ten mittlerweile jede Minute einen Menschen, wie ein wichtiger Bericht \u00fcber die gesundheitlichen Auswirkungen des Klimakollaps zeigt.<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a> Diese Arbeit betont die dringende Notwendigkeit, eine Realit\u00e4t zu \u00fcberwinden, die sowohl l\u00e4hmend als auch t\u00f6dlich ist.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-small-font-size\"><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> <a href=\"https:\/\/www.theguardian.com\/environment\/2025\/oct\/29\/rising-heat-kills-one-person-a-minute-worldwide-lancet-countdown\">https:\/\/www.theguardian.com\/environment\/2025\/oct\/29\/rising-heat-kills-one-person-a-minute-worldwide-lancet-countdown<\/a> [abgerufen: 1. November 2025]<br><br>Fotomontagen: Mateusz Niechoda<br><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Out of the Passage to Seize Back the Sky (documentation)\" src=\"https:\/\/player.vimeo.com\/video\/1199000697?dnt=1&amp;app_id=122963\" width=\"700\" height=\"394\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026, video documentation.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1024x683.jpg\" alt=\"\" class=\"wp-image-7693\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1024x683.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-300x200.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-768x512.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1536x1024.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1920x1280.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1210x807.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-1150x767.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-834x556.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-414x276.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03-360x240.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_03.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oliver Ressler.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1024x683.jpg\" alt=\"\" class=\"wp-image-7697\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1024x683.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-300x200.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-768x512.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1536x1024.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1920x1280.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1210x807.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-1150x767.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-834x556.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-414x276.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06-360x240.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_06.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oliver Ressler.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1024x683.jpg\" alt=\"\" class=\"wp-image-7691\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1024x683.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-300x200.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-768x512.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1536x1024.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1920x1280.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1210x807.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-1150x767.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-834x556.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-414x276.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02-360x240.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_02.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oliver Ressler.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"711\" src=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1024x711.jpg\" alt=\"\" class=\"wp-image-7695\" srcset=\"https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1024x711.jpg 1024w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-300x208.jpg 300w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-768x533.jpg 768w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1536x1067.jpg 1536w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1920x1334.jpg 1920w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1210x840.jpg 1210w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-1150x799.jpg 1150w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-834x579.jpg 834w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-414x288.jpg 414w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04-360x250.jpg 360w, https:\/\/www.ressler.at\/wp-content\/uploads\/2026\/02\/Out_of_the_Passage_photo_Oliver_Ressler_04.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u201cOut of the Passage to Seize Back the Sky\u201d, 2026. Installation view: \u201cGreen Line\u201d, European Capital of Culture Tren\u010d\u00edn 2026. Photo: Oliver Ressler.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Installation im \u00f6ffentlichen Raum von Oliver Ressler Die f\u00fcnf Leuchtk\u00e4sten, die in der unterirdischen Fu\u00dfg\u00e4ngerpassage von Tren\u010d\u00edn installiert sind, sind der Beitrag des \u00f6sterreichischen K\u00fcnstlers Oliver Ressler zu &#8220;Green Line&#8221;, die Teil der Europ\u00e4ischen Kulturhauptstadt Tren\u010d\u00edn 2026 ist. Die Unterf\u00fchrung, die die Altstadt mit dem Fluss verbindet, ist typisch f\u00fcr die st\u00e4dtische Infrastruktur: ein [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,6,164],"tags":[9,27,8,53,55],"class_list":["post-7681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografische-arbeiten","category-installationen","category-public-space","tag-demokratie","tag-klimakrise","tag-oekologie","tag-oekonomie","tag-widerstand"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/posts\/7681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/comments?post=7681"}],"version-history":[{"count":4,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/posts\/7681\/revisions"}],"predecessor-version":[{"id":7762,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/posts\/7681\/revisions\/7762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/media\/7677"}],"wp:attachment":[{"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/media?parent=7681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/categories?post=7681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ressler.at\/de\/wp-json\/wp\/v2\/tags?post=7681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}